{"id":2832,"date":"2025-12-19T11:29:21","date_gmt":"2025-12-19T10:29:21","guid":{"rendered":"https:\/\/focandf.fr\/?p=2832"},"modified":"2026-04-07T08:02:48","modified_gmt":"2026-04-07T06:02:48","slug":"la-machine-est-lancee-les-salaries-doivent-savoir","status":"publish","type":"post","link":"https:\/\/focandf.fr\/index.php\/2025\/12\/19\/la-machine-est-lancee-les-salaries-doivent-savoir\/","title":{"rendered":"Centralisation des fonctions du si\u00e8ge : la machine est lanc\u00e9e."},"content":{"rendered":"\n<p><mark style=\"background-color:rgba(0, 0, 0, 0);color:#12557c\" class=\"has-inline-color\">Hier, jeudi 17\/12, Les 27 salari\u00e9s \u00e9lus du CSE \u00e9taient amen\u00e9s <strong>\u00e0 rendre leur avis<\/strong> par <strong>un vote<\/strong> sur le contenu d&rsquo;un projet interne \u00e0 la CR NDF baptis\u00e9 \u00ab\u00a0<strong>Projet Evolution Organisationnelle des six Directions<\/strong> <strong>DMC, DCE, DRHT, DBAI, DRC, DFP<\/strong>.<\/mark><\/p>\n\n\n\n<p>Les \u00e9lus FO-CFDT ont adress\u00e9 une d\u00e9claration \u00e0 la Direction, lue en s\u00e9ance <strong>avant le vote<\/strong>. Vous en trouverez un extrait ci-dessous.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center has-light-green-cyan-background-color has-background has-medium-font-size\"><strong>D\u00e9claration des \u00e9lus FO-CFDT sur le Projet d&rsquo;Evolution Organisationnelle des Directions DMC, DCE, DRHT, DBAI, DRC, DFP.<\/strong><\/h2>\n\n\n\n<p><\/p>\n\n\n\n<p>\u00ab\u00a0<strong>Les \u00e9lus FO-CFDT<\/strong> ne sont pas dupes sur l&rsquo;intention de ce premier mouvement r\u00e9organisationnel qui, en r\u00e9alit\u00e9, est une mise en configuration de la CR NDF afin d&rsquo;annoncer et pr\u00e9parer la seconde \u00e9tape \u00e0 venir d\u00e8s 2026 avec la d\u00e9clinaison concr\u00e8te dans toutes les Caisses R\u00e9gionales du <strong>Projet Groupe Cr\u00e9dit Agricole Ambitions 2030<\/strong>.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Or ce projet national Ambitions 2030 n&rsquo;est rien d&rsquo;autre que <strong>la mise en \u0153uvre de la centralisation<\/strong> ou dit autrement, du regroupement g\u00e9n\u00e9ral de toutes les fonctions supports dont les m\u00e9tiers existent et se pratiquent depuis toujours au sein des 39 caisses R\u00e9gionales vers un, deux ou trois sites d\u00e9di\u00e9s sur le territoire national.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Nous y sommes. Les mots utilis\u00e9s au sein des diff\u00e9rentes instances nationales et m\u00eame au sein de la Caisse R\u00e9gionale Nord de France <strong>ne peuvent plus masquer<\/strong> ce que les salari\u00e9s des fonctions supports ont devant eux<strong>, c\u2019est-\u00e0-dire la fin annonc\u00e9e pour un grand nombre d&rsquo;entre eux de l&rsquo;exercice de leur m\u00e9tier actuel sur le site o\u00f9 ils le pratiquaient jusqu&rsquo;\u00e0 ce jour.<\/strong><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Quand le Directeur G\u00e9n\u00e9ral Laurent Martin annonce lui-m\u00eame dans Infos Nord de France non seulement <strong>une baisse durable des effectifs<\/strong> mais en plus : &nbsp;<em>\u00ab\u00a0le projet du groupe sera un acc\u00e9l\u00e9rateur pour nous permettre de <strong>cr\u00e9er des \u00ab\u00a0usines\u00a0\u00bb<\/strong> au niveau des 39 CR, acc\u00e9l\u00e9rer nos convergences et r\u00e9duire nos couts\u00a0\u00bb,<\/em> vous avez l\u00e0 la confirmation de ce qui attend les salari\u00e9s concern\u00e9s sur le maintien de leur m\u00e9tier l\u00e0 o\u00f9 ils l&rsquo;exercent aujourd&rsquo;hui.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Les m\u00eames mots sont employ\u00e9s dans le document baptis\u00e9 <strong>\u00ab\u00a0Efficacit\u00e9\u00a0\u00bb<\/strong> qui a \u00e9t\u00e9 \u00e9labor\u00e9 par l&rsquo;instance de la FNCA sur le Projet Ambitions 2030 o\u00f9 il apparait en toutes lettres : \u00ab\u00a0<em>Nous ferons converger nos processus et <strong>d\u00e9velopperons des approches industrielles<\/strong> pour gagner en efficacit\u00e9 en veillant \u00e0 pr\u00e9server un \u00e9quilibre des activit\u00e9s sur le territoire<\/em>\u00ab\u00a0.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Le sch\u00e9ma retenu dans ce m\u00eame document vise \u00e0 une <strong>\u00ab\u00a0massification\u00a0\u00bb des op\u00e9rations<\/strong> pour optimiser les prix de revient ou encore la mise en place d&rsquo;organisations \u00e0 la taille critique\u00a0\u00bb.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Ce m\u00eame document pr\u00e9voit <strong>des choix de localisation des sites<\/strong> effectu\u00e9s en cherchant \u00e0 \u00ab\u00a0<em>pr\u00e9server un relatif \u00e9quilibre des bassins de vie dans les r\u00e9gions sur le territoire national\u00a0\u00bb.<\/em><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Y figure \u00e9galement les \u00e9l\u00e9ments basiques de l&rsquo;accompagnement RH des salari\u00e9s concern\u00e9s par des d\u00e9localisations de leurs services en mati\u00e8re notamment de <strong><em>d\u00e9m\u00e9nagement<\/em><\/strong> ou de <strong><em>formation au reclassement<\/em><\/strong> des salari\u00e9s qui ne suivraient pas le transfert de leur activit\u00e9.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Les \u00e9lus FO et CFDT disent clairement les choses : <strong>nous sommes aux portes d&rsquo;un mouvement de centralisation des fonctions support qui va bouleverser la vie professionnelle et personnelle de plusieurs centaines de salari\u00e9s.<\/strong><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Dans ces conditions, consid\u00e9rant que ce premier projet de r\u00e9organisation pr\u00e9sent\u00e9 ce jour en consultation CSE <strong>porte d\u00e9j\u00e0 en lui<\/strong> les impacts majeurs de la disparition des m\u00e9tiers et ses cons\u00e9quences humaines pour des centaines de salari\u00e9s, les \u00e9lus FO-CFDT <strong>voteront \u00e9videmment \u00ab\u00a0contre\u00a0\u00bb ce projet<\/strong> et indique clairement leur volont\u00e9 de passer en revue <strong>toutes les obligations juridiques et sociales qui incombent \u00e0 l&#8217;employeur<\/strong> dans la perspective de ce virage social d&rsquo;une ampleur sans pr\u00e9c\u00e9dent.\u00a0\u00bb<\/p>\n\n\n\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-8cf370e7 wp-block-group-is-layout-flex\">\n<p>Fin de d\u00e9claration. Merci de votre attention.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">Passage au vote et r\u00e9sultat <\/mark><\/strong>:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"has-medium-font-size\">\u00ab\u00a0<strong>Contre<\/strong>\u00a0\u00bb : FO-CFDT avec 14 voix.<\/li>\n\n\n\n<li class=\"has-medium-font-size\">\u00ab\u00a0<strong>Contre<\/strong>\u00a0\u00bb : UNSA avec 1 voix<\/li>\n\n\n\n<li class=\"has-medium-font-size\">\u00ab\u00a0<strong>Pour<\/strong>\u00a0\u00bb : SNECA\/CGC avec 12 voix<\/li>\n<\/ul>\n\n\n\n<p>L&rsquo;avis consultatif rendu est donc \u00ab\u00a0<strong>d\u00e9favorable<\/strong>\u00a0\u00bb avec 15 voix \u00ab\u00a0<strong>Contre<\/strong>\u00a0\u00bb et 12 voix \u00ab\u00a0<strong>Pour<\/strong>\u00ab\u00a0<\/p>\n\n\n\n<p><\/p>\n<\/div>\n\n\n\n<p class=\"has-light-green-cyan-background-color has-background\"><strong>En conclusion<\/strong> : Ce projet local NDF est donc une simple \u00e9tape annonciatrice de ce qui va suivre tr\u00e8s vite avec un calendrier 2026 d\u00e9j\u00e0 pr\u00e9vu sur la poursuite de la cr\u00e9ation <strong>\u00ab\u00a0d&rsquo;usines<\/strong>\u00a0\u00bb centralisant l<strong>es fonctions supports<\/strong> des Si\u00e8ges dans toutes les CR. Il concerne \u00e9videmment les coll\u00e8gues des deux si\u00e8ges de Lille et Arras. Mais au-del\u00e0 de la diff\u00e9rence de m\u00e9tiers que nous exer\u00e7ons dans l&rsquo;entreprise entre le R\u00e9seau et le Si\u00e8ge, <strong>FO-CFDT <\/strong>en appelle \u00e0 nous sentir vraiment <strong>solidaires<\/strong> avec ce qui concerne les uns aujourd&rsquo;hui et ce qui concernera les autres demain o\u00f9 <strong>l&rsquo;ensemble du mod\u00e8le bancaire<\/strong> que nous connaissons acc\u00e9l\u00e8re vers une mutation radicale avec des enjeux sociaux d&rsquo;une ampleur in\u00e9dite.<\/p>\n\n\n\n<p>Les salari\u00e9s ont un contrat et des obligations mais <strong>ils ont aussi des droits<\/strong>. C&rsquo;est bien ce que nous comptons d\u00e9fendre.<\/p>\n\n\n\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-8cf370e7 wp-block-group-is-layout-flex\">\n<p>Merci de votre attention.<\/p>\n\n\n\n<p><strong>Les \u00e9lus FO-CFDT<\/strong><\/p>\n<\/div>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hier, jeudi 17\/12, Les 27 salari\u00e9s \u00e9lus du CSE \u00e9taient amen\u00e9s \u00e0 rendre leur avis par un vote sur le&hellip;<\/p>\n","protected":false},"author":1,"featured_media":2847,"comment_status":"closed","ping_status":"open","sticky":true,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[28],"tags":[],"class_list":["post-2832","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actu-interne"],"_links":{"self":[{"href":"https:\/\/focandf.fr\/index.php\/wp-json\/wp\/v2\/posts\/2832","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/focandf.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/focandf.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/focandf.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/focandf.fr\/index.php\/wp-json\/wp\/v2\/comments?post=2832"}],"version-history":[{"count":13,"href":"https:\/\/focandf.fr\/index.php\/wp-json\/wp\/v2\/posts\/2832\/revisions"}],"predecessor-version":[{"id":2936,"href":"https:\/\/focandf.fr\/index.php\/wp-json\/wp\/v2\/posts\/2832\/revisions\/2936"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/focandf.fr\/index.php\/wp-json\/wp\/v2\/media\/2847"}],"wp:attachment":[{"href":"https:\/\/focandf.fr\/index.php\/wp-json\/wp\/v2\/media?parent=2832"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/focandf.fr\/index.php\/wp-json\/wp\/v2\/categories?post=2832"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/focandf.fr\/index.php\/wp-json\/wp\/v2\/tags?post=2832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}